{"id":2886,"date":"2024-11-13T10:37:21","date_gmt":"2024-11-13T10:37:21","guid":{"rendered":"https:\/\/hawkcell.com\/?page_id=2886"},"modified":"2024-11-21T08:41:09","modified_gmt":"2024-11-21T08:41:09","slug":"lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia","status":"publish","type":"page","link":"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/","title":{"rendered":"L&rsquo;IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l&rsquo;IA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-landing-page.php","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-2886","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l&#039;IA - HawkCell<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l&#039;IA - HawkCell\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/\" \/>\n<meta property=\"og:site_name\" content=\"HawkCell\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-21T08:41:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hawkcell.com\\\/fr\\\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\\\/\",\"url\":\"https:\\\/\\\/hawkcell.com\\\/fr\\\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\\\/\",\"name\":\"L'IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l'IA - HawkCell\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hawkcell.com\\\/#website\"},\"datePublished\":\"2024-11-13T10:37:21+00:00\",\"dateModified\":\"2024-11-21T08:41:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hawkcell.com\\\/fr\\\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hawkcell.com\\\/fr\\\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hawkcell.com\\\/fr\\\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hawkcell.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l&#8217;IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hawkcell.com\\\/#website\",\"url\":\"https:\\\/\\\/hawkcell.com\\\/\",\"name\":\"HawkCell\",\"description\":\"Shaping the Future of MRI for Animals\",\"publisher\":{\"@id\":\"https:\\\/\\\/hawkcell.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hawkcell.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hawkcell.com\\\/#organization\",\"name\":\"HawkCell\",\"url\":\"https:\\\/\\\/hawkcell.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hawkcell.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hawkcell.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/screenshot.png\",\"contentUrl\":\"https:\\\/\\\/hawkcell.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/screenshot.png\",\"width\":1200,\"height\":900,\"caption\":\"HawkCell\"},\"image\":{\"@id\":\"https:\\\/\\\/hawkcell.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hawkcell\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l'IA - HawkCell","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/","og_locale":"fr_FR","og_type":"article","og_title":"L'IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l'IA - HawkCell","og_url":"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/","og_site_name":"HawkCell","article_modified_time":"2024-11-21T08:41:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/","url":"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/","name":"L'IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l'IA - HawkCell","isPartOf":{"@id":"https:\/\/hawkcell.com\/#website"},"datePublished":"2024-11-13T10:37:21+00:00","dateModified":"2024-11-21T08:41:09+00:00","breadcrumb":{"@id":"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hawkcell.com\/fr\/lirm-dans-la-recherche-preclinique-nouvelles-perspectives-avec-des-solutions-basees-sur-lia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hawkcell.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;IRM dans la recherche pr\u00e9clinique : Nouvelles perspectives avec des solutions bas\u00e9es sur l&#8217;IA"}]},{"@type":"WebSite","@id":"https:\/\/hawkcell.com\/#website","url":"https:\/\/hawkcell.com\/","name":"HawkCell","description":"Shaping the Future of MRI for Animals","publisher":{"@id":"https:\/\/hawkcell.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hawkcell.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hawkcell.com\/#organization","name":"HawkCell","url":"https:\/\/hawkcell.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hawkcell.com\/#\/schema\/logo\/image\/","url":"https:\/\/hawkcell.com\/wp-content\/uploads\/2022\/09\/screenshot.png","contentUrl":"https:\/\/hawkcell.com\/wp-content\/uploads\/2022\/09\/screenshot.png","width":1200,"height":900,"caption":"HawkCell"},"image":{"@id":"https:\/\/hawkcell.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/hawkcell\/"]}]}},"_links":{"self":[{"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/pages\/2886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/comments?post=2886"}],"version-history":[{"count":3,"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/pages\/2886\/revisions"}],"predecessor-version":[{"id":2901,"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/pages\/2886\/revisions\/2901"}],"wp:attachment":[{"href":"https:\/\/hawkcell.com\/fr\/wp-json\/wp\/v2\/media?parent=2886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}